{"id":980,"date":"2014-03-05T10:16:51","date_gmt":"2014-03-05T09:16:51","guid":{"rendered":"http:\/\/www.lucaghigliano.it\/it\/?p=980"},"modified":"2015-03-10T11:49:12","modified_gmt":"2015-03-10T10:49:12","slug":"mountain-bike-pietra-ligure","status":"publish","type":"post","link":"http:\/\/www.lucaghigliano.it\/it\/mountain-bike-pietra-ligure\/","title":{"rendered":"[VIDEO] MTB @ Pietra Ligure"},"content":{"rendered":"<div class=\"post-video\"><iframe loading=\"lazy\" src=\"http:\/\/player.vimeo.com\/video\/88633092?title=0&amp;byline=0&amp;portrait=0\" width=\"700\" height=\"500\" frameborder=\"0\"><\/iframe><\/div>\n<p>Sull&#8217;onda di ottimismo che si \u00e8 creata durante la realizzazione dell&#8217;articolo per il numero di Marzo di <a href=\"http:\/\/www.mountain-biking.it\/\" target=\"_blank\">MountainBiking<\/a> Italia siamo tornati al lavoro qualche settimana dopo, sempre in compagnia di Igor e Gianni di <a href=\"http:\/\/www.ariaperta.info\" target=\"_blank\">AriAperta<\/a> e Andrea di <a href=\"http:\/\/www.aswildasyou.eu\" target=\"_blank\">AWAY<\/a>, per la realizzazione di un video di promozione del territorio e delle attivit\u00e0 dei ragazzi di Pietra Ligure.<br \/>\n<!--more-->E&#8217; stato un lavoro molto impegnativo che ci ha visti sul campo per due giorni consecutivi di riprese tra sentieri, salti e boschi silenziosi. Il team si \u00e8 dimostrato molto affiatato, lavorando duramente ma sempre con il sorriso sulle labbra e la voglia di ridere e scherzare. Un volta rientrati alla base \u00e8 iniziata poi la fase di montaggio e post-produzione che ha richiesto alcuni giorni ed un numero considerevole di modifiche e telefonate Piemonte &#8211; Liguria&#8230; Ma alla fine quello che conta \u00e8 che il cliente sia soddisfatto per il risultato ottenuto!!!<\/p>\n<h2><a href=\"https:\/\/vimeo.com\/88633092\" target=\"_blank\">MOUNTAIN BIKE @ PIETRA LIGURE on VIMEO<\/a><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-983\" style=\"line-height: 1.5em;\" src=\"http:\/\/www.lucaghigliano.it\/it\/wp-content\/uploads\/2014\/04\/1613827_10152301015011983_1124464205_n.jpg\" alt=\"1613827_10152301015011983_1124464205_n\" width=\"816\" height=\"958\" srcset=\"http:\/\/www.lucaghigliano.it\/it\/wp-content\/uploads\/2014\/04\/1613827_10152301015011983_1124464205_n.jpg 816w, http:\/\/www.lucaghigliano.it\/it\/wp-content\/uploads\/2014\/04\/1613827_10152301015011983_1124464205_n-255x300.jpg 255w\" sizes=\"(max-width: 816px) 100vw, 816px\" \/><\/p>\n<p>&#8211; 2 Fujifilm X10\/20 per riprese statiche<br \/>\n&#8211; 3 GoPro III per le riprese on-bike<br \/>\n&#8211; 1 Kodak ZX3 per le riprese &#8220;acquatiche&#8221;<br \/>\n&#8211; 2 cavalletti Manfrotto per riprese video leggere<br \/>\n&#8211; 1 gimbal Genius<br \/>\n&#8211; 1 braccio GoPro<br \/>\n&#8211; 1 GoPro chest mount<br \/>\n&#8211; 1 Gorillapod<br \/>\n&#8211; 1 braccio Manfrotto<br \/>\n&#8211; 1 ProBook HP<br \/>\n&#8211; 1 drone per riprese aeree fullHD<br \/>\n&#8211; 1 inarrestabile Panda 4&#215;4 &#8211; quella vera<br \/>\n&#8211; 3 bikers + relative bici [Specialized Stumpjumper &#8211; Cannondale Lefty 27.5 e Lefty 29]<br \/>\n&#8211; quasi 20Gb di filmati<br \/>\n&#8211; 43h di montaggi video<\/p>\n<p>Un ringraziamento a tutti coloro che hanno partecipato e alla prossima avventura!!! CiAoOo &#8211; Luca<\/p>\n<p>________________________________________<\/p>\n<p><strong>Se hai trovato interessante questo articolo e vuoi ricevere informazioni, prove\u00a0e aggiornamenti su temi\u00a0fotografici iscriviti alla newsletter mensile. Non sono il tipo che intasa le caselle di posta infatti\u00a0<em>invio massimo una mail\/mese<\/em>. Usa il <a title=\"CONTATTI\" href=\"http:\/\/www.lucaghigliano.it\/it\/contatti\/\" target=\"_blank\">modulo\u00a0di iscrizione<\/a> oppure contattami all\u2019indirizzo\u00a0<a href=\"mailto:luca@lucaghigliano.it\">luca@lucaghigliano.it<\/a> con oggetto \u201cNewsLetter\u201d :)<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>Se ti \u00e8 piaciuto questo articolo puoi\u00a0contribuire anche tu alla crescita del sito\u00a0cliccando su uno dei tasti di FaceBook qua sotto\u2026 oppure su entrambi! Grazie 1000 anticipatamente :)<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sull&#8217;onda di ottimismo che si \u00e8 creata durante la realizzazione dell&#8217;articolo per il numero di&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[82,63,85,64],"_links":{"self":[{"href":"http:\/\/www.lucaghigliano.it\/it\/wp-json\/wp\/v2\/posts\/980"}],"collection":[{"href":"http:\/\/www.lucaghigliano.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.lucaghigliano.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.lucaghigliano.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lucaghigliano.it\/it\/wp-json\/wp\/v2\/comments?post=980"}],"version-history":[{"count":10,"href":"http:\/\/www.lucaghigliano.it\/it\/wp-json\/wp\/v2\/posts\/980\/revisions"}],"predecessor-version":[{"id":2541,"href":"http:\/\/www.lucaghigliano.it\/it\/wp-json\/wp\/v2\/posts\/980\/revisions\/2541"}],"wp:attachment":[{"href":"http:\/\/www.lucaghigliano.it\/it\/wp-json\/wp\/v2\/media?parent=980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.lucaghigliano.it\/it\/wp-json\/wp\/v2\/categories?post=980"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.lucaghigliano.it\/it\/wp-json\/wp\/v2\/tags?post=980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}